{"id":1053897,"date":"2026-07-15T13:52:34","date_gmt":"2026-07-15T05:52:34","guid":{"rendered":"https:\/\/vimaterial.de\/problemi-comuni-relativi-ai-target-di-sputtering-ito-e-relative-soluzioni\/"},"modified":"2026-07-15T13:57:16","modified_gmt":"2026-07-15T05:57:16","slug":"problemi-comuni-relativi-ai-target-di-sputtering-ito-e-relative-soluzioni","status":"publish","type":"post","link":"https:\/\/vimaterial.de\/it\/problemi-comuni-relativi-ai-target-di-sputtering-ito-e-relative-soluzioni\/","title":{"rendered":"Problemi comuni relativi ai target di sputtering ITO e relative soluzioni"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1053897\" class=\"elementor elementor-1053897 elementor-1053886\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e218fab e-flex e-con-boxed e-con e-parent\" data-id=\"e218fab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b44820 elementor-widget elementor-widget-heading\" data-id=\"1b44820\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Che cos\u2019\u00e8 un bersaglio di sputtering in ossido di indio e stagno (ITO)?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1081715 elementor-widget elementor-widget-text-editor\" data-id=\"1081715\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/vimaterial.de\/it\/product\/ossido-di-indio-e-stagno-ito-2\/\">bersaglio di sputtering all&#8217;ossido di indio e stagno (ITO)<\/a><\/span> \u00e8 un materiale ossido conduttivo trasparente (TCO) ampiamente utilizzato per il deposito di film conduttivi trasparenti. La composizione standard \u00e8 costituita dal 90% in peso di ossido di indio (In\u2082O\u2083) e dal 10% in peso di ossido di stagno (SnO\u2082), un rapporto accuratamente ottimizzato per ottenere un eccellente equilibrio tra conduttivit\u00e0 elettrica e trasparenza ottica.<\/p><p>Piuttosto che una semplice miscela, l\u2019ITO \u00e8 un materiale ceramico progettato con precisione. L\u2019ossido di indio \u00e8 un semiconduttore di tipo n con un ampio gap di banda di circa 3,6 eV, che consente un\u2019elevata trasmissione della luce visibile fornendo al contempo una buona conduttivit\u00e0 elettrica grazie agli elettroni liberi. L\u2019ossido di stagno funge da dopante che aumenta la concentrazione dei portatori nell\u2019ossido di indio, riducendo significativamente la resistivit\u00e0 elettrica senza compromettere la trasparenza.<\/p><p>La combinazione di In\u2082O\u2083 e SnO\u2082 stabilizza inoltre il materiale riducendo le fluttuazioni di conduttivit\u00e0 causate dai vuoti di ossigeno. Di conseguenza, i film di ITO presentano eccellenti prestazioni elettriche, un\u2019elevata trasmittanza ottica e una straordinaria stabilit\u00e0 a lungo termine.<\/p><p>Grazie a queste propriet\u00e0, <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/vimaterial.de\/it\/search\/?type=name&#038;keyword=ITO\">l\u2019ITO<\/a><\/span> rimane uno dei materiali conduttivi trasparenti pi\u00f9 utilizzati per applicazioni quali:<\/p><ul><li>Schermi piatti<\/li><li>Schermi tattili<\/li><li><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/en.wikipedia.org\/wiki\/OLED\" rel=\"nofollow noopener\" target=\"_blank\">dispositivi<\/a><\/span> Dispositivi<\/li><li>Celle solari<\/li><li>Vetro a bassa emissivit\u00e0 (Low-E)<\/li><li>Finestre intelligenti<\/li><li>Rivestimenti ottici<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a3bf8d elementor-widget elementor-widget-image\" data-id=\"0a3bf8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"753\" height=\"500\" src=\"https:\/\/vimaterial.de\/wp-content\/uploads\/2026\/07\/ITO-sputtering-Target.jpg\" class=\"attachment-large size-large wp-image-1053898\" alt=\"Target per sputtering ITO - VIMATERIAL\" srcset=\"https:\/\/vimaterial.de\/wp-content\/uploads\/2026\/07\/ITO-sputtering-Target.jpg 753w, https:\/\/vimaterial.de\/wp-content\/uploads\/2026\/07\/ITO-sputtering-Target-300x199.jpg 300w, https:\/\/vimaterial.de\/wp-content\/uploads\/2026\/07\/ITO-sputtering-Target-600x398.jpg 600w\" sizes=\"(max-width: 753px) 100vw, 753px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e704d6 elementor-widget elementor-widget-heading\" data-id=\"0e704d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Problemi comuni e soluzioni durante la deposizione di film sottili di ITO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4bd7bf elementor-widget elementor-widget-heading\" data-id=\"d4bd7bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A. Distacco e screpolatura della pellicola<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3450484 elementor-widget elementor-widget-text-editor\" data-id=\"3450484\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La delaminazione e la formazione di crepe nel film sono tra i problemi pi\u00f9 comuni riscontrati durante la deposizione di film sottili di ITO. Questi difetti riducono la conduttivit\u00e0, le prestazioni ottiche e l&#8217;affidabilit\u00e0 meccanica, accorciando in ultima analisi la durata dei componenti rivestiti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1299a0c elementor-widget elementor-widget-heading\" data-id=\"1299a0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Cause<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c22d358 elementor-widget elementor-widget-text-editor\" data-id=\"c22d358\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>1. Tensione residua<\/strong><\/p><p>Le tensioni residue si generano a causa della differenza tra i coefficienti di dilatazione termica del film di ITO e del substrato. Durante la deposizione ad alta temperatura e il successivo raffreddamento, all\u2019interno del film si accumulano tensioni termiche. Tensioni eccessive possono causare la formazione di crepe o la completa delaminazione del film, in particolare sui substrati flessibili.<\/p><p><strong>2. Preparazione inadeguata del substrato<\/strong><\/p><p>Contaminanti quali grasso, polvere, umidit\u00e0 o strati di ossido nativo riducono l\u2019adesione del film. Se la superficie del substrato non viene adeguatamente pulita o attivata prima della deposizione, la forza di adesione tra il substrato e il rivestimento ITO diminuisce in modo significativo.<\/p><p><strong>3. Spessore eccessivo del film<\/strong><\/p><p>La deposizione di uno strato di ITO eccessivamente spesso in un unico processo aumenta la tensione interna. I film spessi sono inoltre pi\u00f9 sensibili alle sollecitazioni meccaniche durante la flessione, i cicli termici o gli urti, rendendo pi\u00f9 probabile la formazione di crepe.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd4a3a1 elementor-widget elementor-widget-heading\" data-id=\"dd4a3a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Soluzioni<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f2668c elementor-widget elementor-widget-text-editor\" data-id=\"8f2668c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>1. Ottimizzare i parametri di deposizione<\/strong><\/p><p>Abbassare la temperatura di deposizione quando possibile e controllare attentamente lo spessore del film. La deposizione multistrato con ricottura intermedia \u00e8 un approccio efficace per alleviare le tensioni residue.<\/p><p><strong>2. Migliorare il trattamento superficiale del substrato<\/strong><\/p><p>Utilizzare la pulizia al plasma, il trattamento con ozono UV o l\u2019incisione chimica per rimuovere le impurit\u00e0 e attivare la superficie del substrato. Una corretta preparazione della superficie migliora notevolmente l\u2019adesione del film.<\/p><p><strong>3. Controllare lo spessore del film<\/strong><\/p><p>Ottimizzare la velocit\u00e0 di deposizione ed evitare di depositare rivestimenti eccessivamente spessi in un unico ciclo. La ricottura post-deposizione pu\u00f2 alleviare ulteriormente le tensioni interne e migliorare la durata del film.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b28b5b7 elementor-widget elementor-widget-heading\" data-id=\"b28b5b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">B. Spessore non uniforme del film<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfccdd2 elementor-widget elementor-widget-text-editor\" data-id=\"cfccdd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una scarsa uniformit\u00e0 dello spessore influisce non solo sulla resistenza di foglio, ma anche sulla trasmittanza ottica, causando prestazioni incostanti del dispositivo e guasti localizzati.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddd52fb elementor-widget elementor-widget-heading\" data-id=\"ddd52fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Cause<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfe9844 elementor-widget elementor-widget-text-editor\" data-id=\"bfe9844\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>1. Progettazione delle apparecchiature di deposizione<\/strong><\/p><p>Una distribuzione non uniforme del materiale pu\u00f2 derivare da un posizionamento errato del bersaglio, dalla geometria di sputtering, dal posizionamento della sorgente di evaporazione o dalla progettazione dell\u2019ugello, specialmente quando si rivestono substrati di ampia superficie.<\/p><p><strong>2. Parametri di processo instabili<\/strong><\/p><p>Le variazioni della potenza di sputtering, della pressione nella camera, della portata del gas o del tempo di deposizione influenzano direttamente la velocit\u00e0 di deposizione, determinando uno spessore non uniforme del film su tutto il substrato.<\/p><p><strong>3. Movimento irregolare del substrato<\/strong><\/p><p>Durante la deposizione, i substrati vengono in genere ruotati o traslati per migliorare l\u2019uniformit\u00e0 del rivestimento. Un movimento irregolare, una velocit\u00e0 di rotazione errata o un allineamento inadeguato possono causare una distribuzione non uniforme del materiale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-044d474 elementor-widget elementor-widget-heading\" data-id=\"044d474\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Soluzioni<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cf9bbb elementor-widget elementor-widget-text-editor\" data-id=\"1cf9bbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>1. Ottimizzare la configurazione delle apparecchiature<\/strong><\/p><p>Regolare il posizionamento del bersaglio, la geometria di sputtering e l\u2019allineamento della sorgente per migliorare l\u2019uniformit\u00e0 del rivestimento. I portasubstrati rotanti e i sistemi di movimento multiasse sono particolarmente efficaci per le applicazioni di rivestimento su grandi superfici.<\/p><p><strong>2. Mantenere condizioni di processo stabili<\/strong><\/p><p>Monitorare e controllare con precisione i parametri chiave quali la potenza di sputtering, la pressione della camera, la portata del gas e il tempo di deposizione. Il controllo di processo a circuito chiuso \u00e8 in grado di compensare automaticamente le fluttuazioni dei parametri e di mantenere una velocit\u00e0 di deposizione stabile.<\/p><p><strong>3. Ottimizzare il movimento del substrato<\/strong><\/p><p>Regolare con cura la velocit\u00e0 di rotazione del substrato, la traiettoria di movimento e il posizionamento per garantire una deposizione uniforme del materiale. I sistemi di movimentazione del substrato multiasse possono migliorare significativamente l\u2019uniformit\u00e0 del rivestimento su superfici estese.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39f5feb elementor-widget elementor-widget-heading\" data-id=\"39f5feb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">C. Fattori ambientali che influenzano la deposizione del film di ITO<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ddd996 elementor-widget elementor-widget-text-editor\" data-id=\"3ddd996\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Condizioni ambientali quali l&#8217;umidit\u00e0, le variazioni di temperatura e la contaminazione della camera possono influire in modo significativo sulla qualit\u00e0 del film. Un controllo ambientale inadeguato pu\u00f2 ridurre la conduttivit\u00e0, la trasparenza e l&#8217;uniformit\u00e0 del rivestimento, aumentando al contempo i difetti di produzione.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4f0877 elementor-widget elementor-widget-heading\" data-id=\"a4f0877\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Cause<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-992453f elementor-widget elementor-widget-text-editor\" data-id=\"992453f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>1. Elevata umidit\u00e0<\/strong><\/p><p>Il vapore acqueo pu\u00f2 adsorbirsi sul substrato o sul film in formazione durante la deposizione, riducendo la densit\u00e0 del film e compromettendone le propriet\u00e0 sia elettriche che ottiche. L\u2019umidit\u00e0 pu\u00f2 inoltre favorire reazioni chimiche indesiderate che compromettono la stabilit\u00e0 del film.<\/p><p><strong>2. Variazioni di temperatura<\/strong><\/p><p>Le variazioni della temperatura ambiente o di processo influenzano la cinetica di crescita del film e la sua microstruttura. Eccessive variazioni di temperatura possono aumentare la tensione residua, causando crepe o delaminazione, mentre temperature troppo basse possono ostacolare la cristallizzazione e ridurre la qualit\u00e0 del film.<\/p><p><strong>3. Gas contaminanti<\/strong><\/p><p>L\u2019ossigeno residuo, l\u2019azoto, il vapore acqueo o altri contaminanti all\u2019interno della camera di deposizione possono reagire con il film depositato, alterandone le propriet\u00e0 elettriche e ottiche. Anche tracce minime di contaminanti possono creare difetti localizzati in condizioni di alto vuoto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2806f27 elementor-widget elementor-widget-heading\" data-id=\"2806f27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Soluzioni<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83684ef elementor-widget elementor-widget-text-editor\" data-id=\"83684ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>1. Mantenere un ambiente sottovuoto di alta qualit\u00e0<\/strong><\/p><p>Un sistema di alto vuoto stabile \u00e8 essenziale per la produzione di rivestimenti ITO di alta qualit\u00e0. Migliorare l\u2019efficienza di pompaggio e utilizzare setacci molecolari o trappole a freddo per rimuovere l\u2019umidit\u00e0 residua. Anche la pulizia regolare della camera contribuisce a ridurre al minimo la contaminazione.<\/p><p><strong>2. Controllare la temperatura di processo<\/strong><\/p><p>Mantenere una temperatura di deposizione stabile durante tutto il processo di rivestimento utilizzando sistemi di riscaldamento o raffreddamento adeguati. Un controllo costante della temperatura favorisce una crescita uniforme del film e riduce le tensioni residue.<\/p><p><strong>3. Ridurre al minimo le fonti di contaminazione<\/strong><\/p><p>Utilizzare gas di processo ad elevata purezza, installare sistemi di filtrazione dei gas efficienti e monitorare regolarmente la pulizia della camera. Il mantenimento di un ambiente di deposizione pulito migliora significativamente la qualit\u00e0 del film, la riproducibilit\u00e0 e la resa produttiva.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94f479d elementor-widget elementor-widget-heading\" data-id=\"94f479d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conclusione<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86c4097 elementor-widget elementor-widget-text-editor\" data-id=\"86c4097\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il successo della deposizione di film sottili di ITO dipende dall\u2019ottimizzazione combinata della qualit\u00e0 dei materiali, dei parametri di deposizione, della configurazione delle apparecchiature, della preparazione del substrato e del controllo ambientale. Comprendendo le cause alla radice dei difetti comuni di rivestimento \u2014 tra cui distacco del film, fessurazioni, disomogeneit\u00e0 dello spessore e contaminazione ambientale \u2014 i produttori possono migliorare significativamente le prestazioni del rivestimento, la resa produttiva e l\u2019affidabilit\u00e0 a lungo termine.<\/p><p>La scelta di un bersaglio di sputtering ITO ad alta densit\u00e0 e elevata purezza, unita a parametri di sputtering ottimizzati e a un rigoroso controllo del processo, \u00e8 essenziale per la produzione di film conduttivi trasparenti con eccellente conduttivit\u00e0 elettrica, elevata trasmittanza ottica e durata superiore.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d41cf91 elementor-widget elementor-widget-heading\" data-id=\"d41cf91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Domande frequenti (FAQ)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8f0893 elementor-widget elementor-widget-n-accordion\" data-id=\"b8f0893\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1930\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1930\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Perch\u00e9 un film sottile di ITO si stacca dopo la deposizione? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1930\" class=\"elementor-element elementor-element-6e9ab2e e-con-full e-flex e-con e-child\" data-id=\"6e9ab2e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0511f01 elementor-widget elementor-widget-text-editor\" data-id=\"0511f01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il distacco del film \u00e8 solitamente causato da un&#8217;eccessiva tensione residua, da una pulizia inadeguata del substrato, da una preparazione superficiale insufficiente o da una discrepanza nella dilatazione termica tra il substrato e il rivestimento ITO. L&#8217;ottimizzazione dei parametri di deposizione e il miglioramento del pretrattamento del substrato possono migliorare significativamente l&#8217;adesione del film.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1931\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1931\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Quali sono le cause delle crepe nei rivestimenti ITO? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1931\" class=\"elementor-element elementor-element-3eaf8ea e-con-full e-flex e-con e-child\" data-id=\"3eaf8ea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c935f1a elementor-widget elementor-widget-text-editor\" data-id=\"c935f1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I rivestimenti ITO possono presentare crepe a causa di uno spessore eccessivo dello strato, elevate tensioni interne, sbalzi di temperatura o sollecitazioni meccaniche. L&#8217;utilizzo di rivestimenti multistrato pi\u00f9 sottili e l&#8217;applicazione di un trattamento di ricottura post-deposizione possono ridurre efficacemente il rischio di formazione di crepe.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1932\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1932\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Perch\u00e9 \u00e8 importante un bersaglio di sputtering ITO ad alta purezza? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1932\" class=\"elementor-element elementor-element-6040785 e-con-full e-flex e-con e-child\" data-id=\"6040785\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7f49a8 elementor-widget elementor-widget-text-editor\" data-id=\"c7f49a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I target ITO ad alta purezza contengono un minor numero di impurit\u00e0 e difetti strutturali, garantendo cos\u00ec uno sputtering pi\u00f9 stabile, una minore generazione di particelle, una maggiore uniformit\u00e0 del film, una conduttivit\u00e0 pi\u00f9 elevata e migliori prestazioni ottiche.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1933\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1933\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> In quali settori vengono comunemente utilizzati i target di sputtering in ITO? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1933\" class=\"elementor-element elementor-element-0d35e02 e-flex e-con-boxed e-con e-child\" data-id=\"0d35e02\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cea79ad elementor-widget elementor-widget-text-editor\" data-id=\"cea79ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I bersagli di sputtering ITO trovano ampio impiego nella produzione di schermi piatti, pannelli touch, schermi OLED, celle solari fotovoltaiche, vetri architettonici Low-E, finestre intelligenti, rivestimenti ottici e dispositivi a semiconduttori.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1934\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1934\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Quali fattori occorre prendere in considerazione nella scelta di un bersaglio per sputtering ITO? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1934\" class=\"elementor-element elementor-element-c61c131 e-flex e-con-boxed e-con e-child\" data-id=\"c61c131\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-42d135a elementor-widget elementor-widget-text-editor\" data-id=\"42d135a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tra i fattori importanti da considerare figurano la purezza, la densit\u00e0, la struttura granulare, i rapporti composizionali, le dimensioni del bersaglio, la qualit\u00e0 dell\u2019adesione, la compatibilit\u00e0 con la tecnica di sputtering e il processo di deposizione specifico. La scelta del bersaglio appropriato contribuisce a migliorare la qualit\u00e0 del rivestimento, la stabilit\u00e0 del processo e l\u2019efficienza produttiva.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Che cos\u2019\u00e8 un bersaglio di sputtering in ossido di indio e stagno (ITO)? Un bersaglio di sputtering all&#8217;ossido di indio e stagno (ITO) \u00e8 un materiale ossido conduttivo trasparente (TCO) ampiamente utilizzato per il deposito di film conduttivi trasparenti. La composizione standard \u00e8 costituita dal 90% in peso di ossido di indio (In\u2082O\u2083) e dal [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1053898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[114],"tags":[],"class_list":["post-1053897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"acf":[],"_links":{"self":[{"href":"https:\/\/vimaterial.de\/it\/wp-json\/wp\/v2\/posts\/1053897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vimaterial.de\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vimaterial.de\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vimaterial.de\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/vimaterial.de\/it\/wp-json\/wp\/v2\/comments?post=1053897"}],"version-history":[{"count":2,"href":"https:\/\/vimaterial.de\/it\/wp-json\/wp\/v2\/posts\/1053897\/revisions"}],"predecessor-version":[{"id":1053900,"href":"https:\/\/vimaterial.de\/it\/wp-json\/wp\/v2\/posts\/1053897\/revisions\/1053900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vimaterial.de\/it\/wp-json\/wp\/v2\/media\/1053898"}],"wp:attachment":[{"href":"https:\/\/vimaterial.de\/it\/wp-json\/wp\/v2\/media?parent=1053897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vimaterial.de\/it\/wp-json\/wp\/v2\/categories?post=1053897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vimaterial.de\/it\/wp-json\/wp\/v2\/tags?post=1053897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}